{"id":3831,"date":"2023-10-20T11:09:50","date_gmt":"2023-10-20T09:09:50","guid":{"rendered":"https:\/\/www.icsanbartolomeo.edu.it\/?p=3831"},"modified":"2024-02-07T14:00:20","modified_gmt":"2024-02-07T14:00:20","slug":"proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24","status":"publish","type":"post","link":"https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/","title":{"rendered":"Proclamazione eletti componenti Genitori"},"content":{"rendered":"<p>Proclamazione eletti componenti Genitori nei consigli di intersezione, interclasse e classe a.s. 2023\/24<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proclamazione eletti componenti Genitori nei consigli di intersezione, interclasse e classe a.s. 2023\/24<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[239,265,268],"class_list":["post-3831","post","type-post","status-publish","format-standard","hentry","tag-alunni","tag-genitori","tag-insegnanti","tipologia-articolo-comunicazioni","tipologia-articolo-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Proclamazione eletti componenti Genitori - Istituto Comprensivo Statale &quot;Leonardo Bianchi&quot; - San Bartolomeo in Galdo (BN)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proclamazione eletti componenti Genitori - Istituto Comprensivo Statale &quot;Leonardo Bianchi&quot; - San Bartolomeo in Galdo (BN)\" \/>\n<meta property=\"og:description\" content=\"Proclamazione eletti componenti Genitori nei consigli di intersezione, interclasse e classe a.s. 2023\/24\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/\" \/>\n<meta property=\"og:site_name\" content=\"Istituto Comprensivo Statale &quot;Leonardo Bianchi&quot; - San Bartolomeo in Galdo (BN)\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-20T09:09:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-07T14:00:20+00:00\" \/>\n<meta name=\"author\" content=\"Rosaria Orofino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosaria Orofino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/\",\"url\":\"https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/\",\"name\":\"Proclamazione eletti componenti Genitori - Istituto Comprensivo Statale &quot;Leonardo Bianchi&quot; - San Bartolomeo in Galdo (BN)\",\"isPartOf\":{\"@id\":\"https:\/\/icsanbartolomeo.edu.it\/#website\"},\"datePublished\":\"2023-10-20T09:09:50+00:00\",\"dateModified\":\"2024-02-07T14:00:20+00:00\",\"author\":{\"@id\":\"https:\/\/icsanbartolomeo.edu.it\/#\/schema\/person\/181ebdd753d95a027745e4757c4b2034\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.icsanbartolomeo.edu.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proclamazione eletti componenti Genitori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/icsanbartolomeo.edu.it\/#website\",\"url\":\"https:\/\/icsanbartolomeo.edu.it\/\",\"name\":\"Istituto Comprensivo Statale &quot;Leonardo Bianchi&quot; - San Bartolomeo in Galdo (BN)\",\"description\":\"I.C &quot;Leonardo Bianchi&quot;\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/icsanbartolomeo.edu.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/icsanbartolomeo.edu.it\/#\/schema\/person\/181ebdd753d95a027745e4757c4b2034\",\"name\":\"Rosaria Orofino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/icsanbartolomeo.edu.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8d342f9734e9768ff5d2bcce897ee367?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8d342f9734e9768ff5d2bcce897ee367?s=96&d=mm&r=g\",\"caption\":\"Rosaria Orofino\"},\"url\":\"https:\/\/www.icsanbartolomeo.edu.it\/author\/rosaria\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proclamazione eletti componenti Genitori - Istituto Comprensivo Statale &quot;Leonardo Bianchi&quot; - San Bartolomeo in Galdo (BN)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/","og_locale":"it_IT","og_type":"article","og_title":"Proclamazione eletti componenti Genitori - Istituto Comprensivo Statale &quot;Leonardo Bianchi&quot; - San Bartolomeo in Galdo (BN)","og_description":"Proclamazione eletti componenti Genitori nei consigli di intersezione, interclasse e classe a.s. 2023\/24","og_url":"https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/","og_site_name":"Istituto Comprensivo Statale &quot;Leonardo Bianchi&quot; - San Bartolomeo in Galdo (BN)","article_published_time":"2023-10-20T09:09:50+00:00","article_modified_time":"2024-02-07T14:00:20+00:00","author":"Rosaria Orofino","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Rosaria Orofino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/","url":"https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/","name":"Proclamazione eletti componenti Genitori - Istituto Comprensivo Statale &quot;Leonardo Bianchi&quot; - San Bartolomeo in Galdo (BN)","isPartOf":{"@id":"https:\/\/icsanbartolomeo.edu.it\/#website"},"datePublished":"2023-10-20T09:09:50+00:00","dateModified":"2024-02-07T14:00:20+00:00","author":{"@id":"https:\/\/icsanbartolomeo.edu.it\/#\/schema\/person\/181ebdd753d95a027745e4757c4b2034"},"breadcrumb":{"@id":"https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.icsanbartolomeo.edu.it\/proclamazione-eletti-componenti-genitori-nei-consigli-di-intersezione-interclasse-e-classe-a-s-2023-24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.icsanbartolomeo.edu.it\/"},{"@type":"ListItem","position":2,"name":"Proclamazione eletti componenti Genitori"}]},{"@type":"WebSite","@id":"https:\/\/icsanbartolomeo.edu.it\/#website","url":"https:\/\/icsanbartolomeo.edu.it\/","name":"Istituto Comprensivo Statale &quot;Leonardo Bianchi&quot; - San Bartolomeo in Galdo (BN)","description":"I.C &quot;Leonardo Bianchi&quot;","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/icsanbartolomeo.edu.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/icsanbartolomeo.edu.it\/#\/schema\/person\/181ebdd753d95a027745e4757c4b2034","name":"Rosaria Orofino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/icsanbartolomeo.edu.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8d342f9734e9768ff5d2bcce897ee367?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d342f9734e9768ff5d2bcce897ee367?s=96&d=mm&r=g","caption":"Rosaria Orofino"},"url":"https:\/\/www.icsanbartolomeo.edu.it\/author\/rosaria\/"}]}},"_links":{"self":[{"href":"https:\/\/www.icsanbartolomeo.edu.it\/wp-json\/wp\/v2\/posts\/3831"}],"collection":[{"href":"https:\/\/www.icsanbartolomeo.edu.it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.icsanbartolomeo.edu.it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.icsanbartolomeo.edu.it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.icsanbartolomeo.edu.it\/wp-json\/wp\/v2\/comments?post=3831"}],"version-history":[{"count":2,"href":"https:\/\/www.icsanbartolomeo.edu.it\/wp-json\/wp\/v2\/posts\/3831\/revisions"}],"predecessor-version":[{"id":4918,"href":"https:\/\/www.icsanbartolomeo.edu.it\/wp-json\/wp\/v2\/posts\/3831\/revisions\/4918"}],"wp:attachment":[{"href":"https:\/\/www.icsanbartolomeo.edu.it\/wp-json\/wp\/v2\/media?parent=3831"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.icsanbartolomeo.edu.it\/wp-json\/wp\/v2\/tags?post=3831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}